{"id":4432,"date":"2026-07-15T08:02:26","date_gmt":"2026-07-15T11:02:26","guid":{"rendered":"https:\/\/pilarinvestimentos.com.br\/?p=4432"},"modified":"2026-07-15T10:12:19","modified_gmt":"2026-07-15T13:12:19","slug":"cafe-com-o-especialista-15-07-26","status":"publish","type":"post","link":"https:\/\/pilarinvestimentos.com.br\/en\/cafe-com-o-especialista-15-07-26\/","title":{"rendered":"Caf\u00e9 com o especialista &#8211; 15\/07\/26"},"content":{"rendered":"<h1 class=\"wp-block-heading\">Bom dia!!!<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Procure um assessor da Pilar Investimentos, e entenda como esse cen\u00e1rio pode impactar os seus investimentos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>O Ibovespa<\/strong>, fechou ontem em alta de 0,51% a 176.641 pontos, o S&amp;P fechou em alta de 0,38% a 7.543 pontos, o Nasdaq subiu 0,90% a 26.107 e o Dow Jones subiu 0,02% a 52.508 pontos.<\/li>\n\n\n\n<li>O D\u00f3lar fechou ontem em queda de 1,05% cotado a R$ 5,07 o Euro fechou em queda de 0,74% cotado a R$5,80 e o Bitcoin subiu 2,72% cotado a R$329.889.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cen\u00e1rio Externo<\/strong> : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Os \u00edndices futuros de Nova York<\/strong>, operam em alta nesta quarta-feira (15), ampliando os ganhos da v\u00e9spera, impulsionados por dados de infla\u00e7\u00e3o mais fracos do que o esperado.<\/li>\n\n\n\n<li>As a\u00e7\u00f5es subiram na ter\u00e7a-feira ap\u00f3s o relat\u00f3rio de infla\u00e7\u00e3o de junho refor\u00e7ar as esperan\u00e7as de que o Federal Reserve (Fed) talvez n\u00e3o precise aumentar as taxas de juros de forma t\u00e3o agressiva este ano.<\/li>\n\n\n\n<li>O \u00edndice de pre\u00e7os ao consumidor (CPI) dos EUA caiu 0,4% em junho em rela\u00e7\u00e3o ao m\u00eas anterior, elevando a taxa de infla\u00e7\u00e3o anual para 3,5%. Economistas consultados pela Dow Jones previam uma queda mensal de 0,2% e uma infla\u00e7\u00e3o anual de 3,8%.<\/li>\n\n\n\n<li>Os investidores ter\u00e3o uma quarta-feira movimentada, acompanhando uma nova rodada de resultados corporativos. Est\u00e3o previstos os balan\u00e7os trimestrais de gigantes como United Airlines, Morgan Stanley, Johnson &amp; Johnson e BlackRock, que devem oferecer novos sinais sobre a sa\u00fade da economia e das empresas americanas.<\/li>\n\n\n\n<li>Na ter\u00e7a-feira, os grandes bancos de Wall Street surpreenderam o mercado ao reportarem n\u00fameros acima das expectativas. JPMorgan Chase, Bank of America, Citigroup, Wells Fargo e Goldman Sachs apresentaram desempenhos robustos, refor\u00e7ando a percep\u00e7\u00e3o de resili\u00eancia do setor financeiro.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veja o desempenho dos mercados futuros:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dow Jones Futuro: +0,09%<\/li>\n\n\n\n<li>S&amp;P 500 Futuro: +0,17%<\/li>\n\n\n\n<li>Nasdaq Futuro: +0,43%<strong>\u00a0\u00a0<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>As bolsas europeias<\/strong>, operam em baixa generalizada, com os cont\u00ednuos ataques dos EUA ao Ir\u00e3 afetando negativamente o sentimento dos investidores. A maioria dos setores opera em baixa, com exce\u00e7\u00e3o das a\u00e7\u00f5es de tecnologia.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mercados Europeus :<\/strong> <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>STOXX 600: -0,14%<\/li>\n\n\n\n<li>DAX (Alemanha): -0,76%<\/li>\n\n\n\n<li>FTSE 100 (Reino Unido): -0,22%<\/li>\n\n\n\n<li>CAC 40 (Fran\u00e7a): -0,19%<\/li>\n\n\n\n<li>FTSE MIB (It\u00e1lia): -0,52%<strong>\u00a0<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Os mercados Asi\u00e1ticos<\/strong>, fecharam em alta nesta quarta, recuperando parte das perdas recentes, com destaque para a forte valoriza\u00e7\u00e3o das a\u00e7\u00f5es sul-coreanas.<\/li>\n\n\n\n<li>O \u00edndice Kospi, principal refer\u00eancia da Coreia do Sul, avan\u00e7ou 6,3%, enquanto o Kosdaq, que re\u00fane empresas de menor capitaliza\u00e7\u00e3o, subiu 4%, refletindo o apetite dos investidores por ativos de risco no pa\u00eds.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fechamento \u00c1sia &#8211; Pac\u00edfico<\/strong> :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Shanghai SE (China), -0,29%<\/li>\n\n\n\n<li>Nikkei (Jap\u00e3o): +1,49%<\/li>\n\n\n\n<li>Hang Seng Index (Hong Kong): +1,40%<\/li>\n\n\n\n<li>Nifty 50 (\u00cdndia): 0,00%<\/li>\n\n\n\n<li>ASX 200 (Austr\u00e1lia): +0,37%<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cen\u00e1rio Dom\u00e9stico<\/strong> :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>No Brasil<\/strong>, a agenda desta quarta-feira traz a divulga\u00e7\u00e3o do volume de servi\u00e7os no Brasil, \u00e0s 9h. A expectativa \u00e9 de alta de 0,1% na compara\u00e7\u00e3o mensal e de 0,9% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado. Mais tarde, \u00e0s 14h30, o Banco Central divulga o fluxo cambial semanal, dado importante para avaliar a entrada e sa\u00edda de recursos do pa\u00eds e o comportamento da demanda por moeda estrangeira.<\/li>\n\n\n\n<li>O Ibovespa fechou em alta nesta ter\u00e7a-feira, ultrapassando os 177 mil pontos no melhor momento, ap\u00f3s a divulga\u00e7\u00e3o de dados de pre\u00e7os ao consumidor nos Estados Unidos abaixo das expectativas, que referendaram o apetite a risco nos mercados.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nas commodities<\/strong>, os pre\u00e7os do petr\u00f3leo operam em alta, enquanto as for\u00e7as americanas realizavam mais uma rodada de ataques contra Teer\u00e3 e Washington restabelecia o bloqueio naval aos portos iranianos pr\u00f3ximos ao Estreito de Ormuz.<\/li>\n\n\n\n<li>As cota\u00e7\u00f5es do min\u00e9rio de ferro na China fecharam em alta, com o aumento das preocupa\u00e7\u00f5es com a oferta ap\u00f3s os trabalhadores da mineradora BHP prometerem entrar em greve em um importante porto australiano no dia seguinte.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Petr\u00f3leo WTI, +0,64%, a US$ 79,85 o barril<\/li>\n\n\n\n<li>Petr\u00f3leo Brent, +0,76%, a US$ 85,37 o barril<\/li>\n\n\n\n<li>Min\u00e9rio de ferro negociado na bolsa de Dalian, +1,13%, a 762 iuanes (US$ 112,54)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Criptoativos<\/strong> : O\u00a0Bitcoin\u00a0subiu nesta quarta-feira, tocando brevemente uma m\u00e1xima de tr\u00eas semanas ap\u00f3s um \u00edndice de infla\u00e7\u00e3o dos EUA abaixo do esperado ajudar a aliviar as preocupa\u00e7\u00f5es com uma alta de juros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bitcoin (BTC), +0,22%, a US$ 64.680,60 (em rela\u00e7\u00e3o \u00e0 cota\u00e7\u00e3o de 24 horas atr\u00e1s).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(Com Reuters e Bloomberg)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Um abra\u00e7o, e bons neg\u00f3cios.<br>Danilo Jesus<\/strong><\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Bom dia!!! Procure um assessor da Pilar Investimentos, e entenda como esse cen\u00e1rio pode impactar os seus investimentos. Cen\u00e1rio Externo : Veja o desempenho dos mercados futuros: Mercados Europeus : Fechamento \u00c1sia &#8211; Pac\u00edfico : Cen\u00e1rio Dom\u00e9stico : Criptoativos : O\u00a0Bitcoin\u00a0subiu nesta quarta-feira, tocando brevemente uma m\u00e1xima de tr\u00eas semanas ap\u00f3s um \u00edndice de infla\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3860,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:heading {\"level\":1} -->\n<h1 class=\"wp-block-heading\">Bom dia!!!<\/h1>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Procure um assessor da Pilar Investimentos, e entenda como esse cen\u00e1rio pode impactar os seus investimentos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>O Ibovespa<\/strong>, fechou ontem em queda de 0,20% a 171.688 pontos, o S&amp;P fechou em queda de 0,22% a 7.483 pontos, o Nasdaq caiu 0,66% a 26.040 e o Dow Jones caiu 0,03% a 52.305 pontos.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>O D\u00f3lar fechou ontem em alta de 0,90% cotado a R$ 5,20 o Euro fechou em alta de 0,48% cotado a R$5,92 e o Bitcoin subiu 4,10% cotado a R$315.349.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Cen\u00e1rio Externo<\/strong> : <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Os \u00edndices futuros de Nova York<\/strong>, recuam nesta quinta-feira (2), v\u00e9spera do feriado da Independ\u00eancia dos Estados Unidos, enquanto investidores aguardam a divulga\u00e7\u00e3o do relat\u00f3rio de emprego (payroll) de junho.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>O dado \u00e9 visto como decisivo para calibrar as expectativas sobre a trajet\u00f3ria dos juros americanos, ap\u00f3s declara\u00e7\u00f5es feitas na quarta-feira pelo presidente do Federal Reserve, Kevin Warsh, reduzirem as apostas de um novo aumento das taxas ainda neste ano.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Economistas consultados pela Reuters preveem a cria\u00e7\u00e3o de 110 mil empregos em junho. A Copa do Mundo provavelmente criou milhares de empregos tempor\u00e1rios, aumentando a probabilidade de uma surpresa positiva. A taxa de desemprego deve permanecer est\u00e1vel em 4,3%.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Al\u00e9m do payroll, os investidores acompanham outros indicadores da economia americana nesta quinta-feira. Entre eles, est\u00e3o os pedidos semanais de aux\u00edlio-desemprego, cuja expectativa \u00e9 de 220 mil solicita\u00e7\u00f5es, e os dados de encomendas \u00e0 ind\u00fastria referentes a maio, com proje\u00e7\u00e3o de queda de 1,8% na compara\u00e7\u00e3o mensal.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Veja o desempenho dos mercados futuros:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Dow Jones Futuro: -0,25%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>S&amp;P 500 Futuro: -0,32%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Nasdaq Futuro: -0,53%<strong>&nbsp;<\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>As bolsas europeias<\/strong>, iniciaram o novo m\u00eas sem dire\u00e7\u00e3o \u00fanica nesta quarta-feira. A maioria dos setores operava em leve queda no in\u00edcio das negocia\u00e7\u00f5es, mas as a\u00e7\u00f5es do segmento qu\u00edmico lideravam os ganhos, com alta de quase 1,1%. As montadoras tamb\u00e9m avan\u00e7avam, registrando valoriza\u00e7\u00e3o de 0,42%.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Mercados Europeus :<\/strong> <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>STOXX 600: -0,16%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>DAX (Alemanha): +0,34%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>FTSE 100 (Reino Unido): -0,26%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>CAC 40 (Fran\u00e7a): -0,41%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>FTSE MIB (It\u00e1lia): -0,30%<strong>&nbsp;<\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Os mercados Asi\u00e1ticos<\/strong>, fecharam sem dire\u00e7\u00e3o \u00fanica, com desempenho positivo nas bolsas do Jap\u00e3o, da China e da Coreia do Sul, enquanto Austr\u00e1lia e Hong Kong fecharam no vermelho..<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Fechamento \u00c1sia - Pac\u00edfico<\/strong> :<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Shanghai SE (China), +0,44%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Nikkei (Jap\u00e3o): +0,59%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Hang Seng Index (Hong Kong): -0,63%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Nifty 50 (\u00cdndia): +0,72%<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>ASX 200 (Austr\u00e1lia): -0,64%<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Cen\u00e1rio Dom\u00e9stico<\/strong> :<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>No Brasil<\/strong>, o Banco Central divulga estat\u00edsticas de cr\u00e9dito referentes ao m\u00eas de maio, enquanto o instituto AtlasIntel divulgar\u00e1 uma pesquisa presidencial com 5.000 entrevistas online realizadas entre 25 e 30 de junho.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Do lado pol\u00edtico, nesta quarta est\u00e1 prevista uma sess\u00e3o de debate tem\u00e1tico sobre a jornada de trabalho de 6\u00d71 (PEC 221\/2019) no plen\u00e1rio do Senado, ap\u00f3s solicita\u00e7\u00e3o aprovada pelo plen\u00e1rio. De acordo com o Ita\u00fa, o andamento da emenda depender\u00e1 tanto do Presidente do Senado, que deve encaminhar formalmente a proposta, quanto do presidente da CCJ.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>O Ibovespa fechou em queda nesta ter\u00e7a-feira, confirmando mais um desempenho mensal negativo, mas se afastou da m\u00ednima do dia, registrada ap\u00f3s dados sobre o mercado de trabalho no Brasil mais fracos do que o esperado.&nbsp;<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>\u00cdndice de refer\u00eancia do mercado acion\u00e1rio brasileiro, o Ibovespa caiu 0,68%, a 172.024,12 pontos, acumulando um decl\u00ednio de 1,01% em junho.&nbsp;<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Nas commodities<\/strong>, os pre\u00e7os do petr\u00f3leo operam sem dire\u00e7\u00e3o \u00fanica devido a preocupa\u00e7\u00f5es de que o impasse nas negocia\u00e7\u00f5es entre o Ir\u00e3 e os EUA para um acordo final que ponha fim \u00e0 guerra possa prolongar as interrup\u00e7\u00f5es no fornecimento na importante regi\u00e3o produtora do Oriente M\u00e9dio.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>As cota\u00e7\u00f5es do min\u00e9rio de ferro na China fecharam em baixa, com as novas barreiras comerciais da Uni\u00e3o Europeia \u00e0s importa\u00e7\u00f5es de a\u00e7o afetando negativamente as perspectivas de demanda.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Petr\u00f3leo WTI, -0,41%, a US$ 69,17 o barril<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Petr\u00f3leo Brent, -0,29%, a US$ 72,73 o barril<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Min\u00e9rio de ferro negociado na bolsa de Dalian, -1,68%, a 733 iuanes (US$ 107,89)<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Criptoativos<\/strong> : O Bitcoin recuou levemente na quarta-feira, permanecendo sob press\u00e3o ap\u00f3s registrar perdas expressivas no trimestre, em meio \u00e0 relut\u00e2ncia dos investidores em comprar criptomoedas diante das crescentes expectativas de juros mais altos nos Estados Unidos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Bitcoin (BTC), -0,16%, a US$ 58.540,93 (em rela\u00e7\u00e3o \u00e0 cota\u00e7\u00e3o de 24 horas atr\u00e1s).<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>(Com Reuters e Bloomberg)<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Um abra\u00e7o, e bons neg\u00f3cios.<br>Danilo Jesus<\/strong><\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[36,19],"tags":[],"class_list":["post-4432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","category-cafe-com-o-especialista"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/pilarinvestimentos.com.br\/wp-content\/uploads\/2025\/10\/Cafe-com-o-especialista-07.jpg?fit=1200%2C803&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/posts\/4432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/comments?post=4432"}],"version-history":[{"count":1,"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/posts\/4432\/revisions"}],"predecessor-version":[{"id":4433,"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/posts\/4432\/revisions\/4433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/media\/3860"}],"wp:attachment":[{"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/media?parent=4432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/categories?post=4432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pilarinvestimentos.com.br\/en\/wp-json\/wp\/v2\/tags?post=4432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}